{"id":1016,"date":"2015-06-22T11:15:27","date_gmt":"2015-06-22T10:15:27","guid":{"rendered":"http:\/\/www.amazing-tunisia.com\/fr\/?p=1016"},"modified":"2015-06-22T11:15:27","modified_gmt":"2015-06-22T10:15:27","slug":"tunisair-et-airbus-collaborent-en-matiere-de-formation-a-la-maintenance","status":"publish","type":"post","link":"https:\/\/www.amazing-tunisia.com\/fr\/tunisair-et-airbus-collaborent-en-matiere-de-formation-a-la-maintenance\/","title":{"rendered":"Tunisair et Airbus collaborent en mati\u00e8re de formation \u00e0 la maintenance"},"content":{"rendered":"<figure style=\"width: 648px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.facebook.com\/My.Amazing.Tunisia\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/7\/79\/Tunisair.a320-200.ts-ime.arp.jpg\/800px-Tunisair.a320-200.ts-ime.arp.jpg\" alt=\"Tunisair Airbus A320-200 (TS-IME). Photo Adrian Pingstone\" width=\"648\" height=\"435\" \/><\/a><figcaption class=\"wp-caption-text\">Tunisair Airbus A320-200 (TS-IME). Photo Adrian Pingstone<\/figcaption><\/figure>\n<p><strong>Premi\u00e8re collaboration d\u2019Airbus en Afrique\u00a0en mati\u00e8re de formation \u00e0 la maintenance.<\/strong><!--more--><\/p>\n<p>Airbus et le groupe Tunisair ont sign\u00e9 un accord \u00e0 long terme afin de d\u00e9velopper la formation en mati\u00e8re de maintenance et d\u2019ing\u00e9nierie \u00e0 Tunis. A cet effet, le centre de formation du groupe Tunisair acquerra les outils de formation d\u2019Airbus et les techniques p\u00e9dagogiques en vue de proposer aux OEM* les capacit\u00e9s n\u00e9cessaires en maintenance pour leurs personnels ainsi que pour d\u2019autres op\u00e9rateurs des A320 et A330 dans la r\u00e9gion. La collaboration garantira l\u2019acquisition des comp\u00e9tences gr\u00e2ce \u00e0 un didacticiel de formation de pointe conforme \u00e0 EASA\/Part-147. \u00ab Airbus Competence Training (ACT) \u00bb, b\u00e9n\u00e9ficie d\u2019un appareil Airbus virtuel au sein d\u2019une classe digitale situ\u00e9e dans les \u00e9tablissements du groupe Tunisair.<\/p>\n<p style=\"text-align: justify;\">Cette collaboration comprendra :<br \/>\n&#8211; L\u2019int\u00e9gration de \u00ab Tunisair Technics Training Division \u00bb et de ses instructeurs dans le programme \u00ab Airbus Maintenance Training Organisation Exposition (MTOE) \u00bb<br \/>\n&#8211; Des cours sp\u00e9cialis\u00e9s et certifiant d\u00e9velopp\u00e9s par Airbus seront assur\u00e9s par les instructeurs de A320 et A330 du groupe Tunisair ;<br \/>\n&#8211; Un acc\u00e8s aux outils num\u00e9riques et un avion r\u00e9el dans les \u00e9tablissements MRO* de Tunisair afin d\u2019offrir une formation compl\u00e8te ;<br \/>\n&#8211; La d\u00e9livrance des certificats Airbus.<\/p>\n<p>Sara Rejeb, Pr\u00e9sidente Directrice G\u00e9n\u00e9rale de Tunisair, a d\u00e9clar\u00e9: \u2018\u2019Nous sommes ravis de nous associer \u00e0 Airbus et d\u2019offrir \u00e0 nos sp\u00e9cialistes et aux autres op\u00e9rateurs d\u2019Airbus les meilleures comp\u00e9tences en mati\u00e8re de maintenance.\u2019\u2019<\/p>\n<p style=\"text-align: justify;\">Didier Lux, Executive Vice President, Airbus Customer Services, a d\u00e9clar\u00e9 \u201cNous sommes convaincus que le niveau \u00e9lev\u00e9 des comp\u00e9tences du personnel du groupe Tunisair, ainsi que les ambitions entrepreneuriales de sa direction permettront le d\u00e9veloppement du \u00ab Training by Airbus \u00bb en Tunisie. Cet accord vise \u00e0 d\u00e9velopper un savoir-faire de pointe en maintenance pour tous les op\u00e9rateurs de l\u2019A320 et l\u2019A330 dans la r\u00e9gion.\u201d<\/p>\n<p style=\"text-align: justify;\">Airbus, \u00e0 travers \u00ab Services by Airbus \u00bb offre des solutions de gestion du cycle de vie de l\u2019appareil de bout en bout pour l\u2019ensemble ses clients. Le portefeuille comprend des services autonomes aussi bien que des solutions compl\u00e8tes, y compris les services \u00ab Flight Hour \u00bb et \u00ab Tailored Support Packages \u00bb, des mises \u00e0 niveau, des formations, des solutions \u00e9lectroniques, d\u2019ing\u00e9nierie et de maintenance, des op\u00e9rations de vol et des services de gestion du mat\u00e9riel. Ensemble, ces solutions am\u00e9liorent la sup\u00e9riorit\u00e9 de l\u2019avion en s\u2019adaptant d\u2019une mani\u00e8re continue aux besoins croissants des clients. Avec plus de 40 ans d\u2019exp\u00e9rience dans l\u2019industrie a\u00e9ronautique et un r\u00e9seau international de 2 500 professionnels, Airbus permet \u00e0 ses les clients de b\u00e9n\u00e9ficier d\u2019un savoir-faire et des capacit\u00e9s uniques du constructeur a\u00e9rien et de ses filiales.<\/p>\n<p>* OEM : Original Equipment Manufacturer (fabricant d&rsquo;\u00e9quipement d&rsquo;origine)<br \/>\n* MRO : Maintenance, Repair and Overhaul (maintenance, r\u00e9paration et refonte des avions)<\/p>\n<p style=\"text-align: justify;\"><strong>Source : Communiqu\u00e9.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Premi\u00e8re collaboration d\u2019Airbus en Afrique\u00a0en mati\u00e8re de formation \u00e0 la maintenance.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[1],"tags":[146,147,133,145],"class_list":["post-1016","post","type-post","status-publish","format-standard","hentry","category-news","tag-aeronautique","tag-airbus","tag-aviation","tag-tunisair"],"_links":{"self":[{"href":"https:\/\/www.amazing-tunisia.com\/fr\/wp-json\/wp\/v2\/posts\/1016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amazing-tunisia.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amazing-tunisia.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amazing-tunisia.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amazing-tunisia.com\/fr\/wp-json\/wp\/v2\/comments?post=1016"}],"version-history":[{"count":0,"href":"https:\/\/www.amazing-tunisia.com\/fr\/wp-json\/wp\/v2\/posts\/1016\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.amazing-tunisia.com\/fr\/wp-json\/wp\/v2\/media?parent=1016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amazing-tunisia.com\/fr\/wp-json\/wp\/v2\/categories?post=1016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amazing-tunisia.com\/fr\/wp-json\/wp\/v2\/tags?post=1016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}